{"id":14182,"date":"2025-05-30T03:28:14","date_gmt":"2025-05-30T03:28:14","guid":{"rendered":"https:\/\/www.espowercorp.com\/?page_id=14182"},"modified":"2026-04-08T04:51:31","modified_gmt":"2026-04-08T04:51:31","slug":"ac-power-distribution-unit-pdu","status":"publish","type":"page","link":"https:\/\/www.espowercorp.com\/en\/ac-power-distribution-unit-pdu\/","title":{"rendered":"AC Power Distribution Unit (SW-R)"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"14182\" class=\"elementor elementor-14182\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c611bb0 elementor-section-boxed elementor-section-height-default elementor-section-height-default qodef-elementor-content-no\" data-id=\"c611bb0\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2d2abc5b\" data-id=\"2d2abc5b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2b59f51 elementor-section-boxed elementor-section-height-default elementor-section-height-default qodef-elementor-content-no elementor-invisible\" data-id=\"2b59f51\" data-element_type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;zoomIn&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f60d840\" data-id=\"f60d840\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-90fd9e9 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"90fd9e9\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.espowercorp.com\/en\/nova\/\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1536\" height=\"526\" src=\"https:\/\/www.espowercorp.com\/wp-content\/uploads\/2025\/03\/Nava-logo-1536x526.png\" class=\"attachment-1536x1536 size-1536x1536 wp-image-13636\" alt=\"\" srcset=\"https:\/\/www.espowercorp.com\/wp-content\/uploads\/2025\/03\/Nava-logo-1536x526.png 1536w, https:\/\/www.espowercorp.com\/wp-content\/uploads\/2025\/03\/Nava-logo-300x103.png 300w, https:\/\/www.espowercorp.com\/wp-content\/uploads\/2025\/03\/Nava-logo-1024x351.png 1024w, https:\/\/www.espowercorp.com\/wp-content\/uploads\/2025\/03\/Nava-logo-768x263.png 768w, https:\/\/www.espowercorp.com\/wp-content\/uploads\/2025\/03\/Nava-logo-2048x701.png 2048w, https:\/\/www.espowercorp.com\/wp-content\/uploads\/2025\/03\/Nava-logo-18x6.png 18w, https:\/\/www.espowercorp.com\/wp-content\/uploads\/2025\/03\/Nava-logo-24x8.png 24w, https:\/\/www.espowercorp.com\/wp-content\/uploads\/2025\/03\/Nava-logo-36x12.png 36w, https:\/\/www.espowercorp.com\/wp-content\/uploads\/2025\/03\/Nava-logo-102x35.png 102w\" sizes=\"(max-width: 1536px) 100vw, 1536px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4297644 elementor-widget elementor-widget-heading\" data-id=\"4297644\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-small\">SD-BD-04-01\/Rev.20\/18-03-69<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-56985ec elementor-hidden-phone elementor-section-boxed elementor-section-height-default elementor-section-height-default qodef-elementor-content-no\" data-id=\"56985ec\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-241d6a47\" data-id=\"241d6a47\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8e6e9c7 elementor-widget elementor-widget-heading\" data-id=\"8e6e9c7\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-medium\">AC POWER DISTRIBUTION (PDU)<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-43cd4aba elementor-widget elementor-widget-easymeals_core_separator\" data-id=\"43cd4aba\" data-element_type=\"widget\" data-widget_type=\"easymeals_core_separator.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m  qodef-separator clear\">\n\t<div class=\"qodef-m-line\" style=\"border-color: #0A79A1;border-style: solid;width: 70px;border-bottom-width: 3px\"><\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5d85553 elementor-section-boxed elementor-section-height-default elementor-section-height-default qodef-elementor-content-no elementor-invisible\" data-id=\"5d85553\" data-element_type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeInDown&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-49febd8\" data-id=\"49febd8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-34609324 elementor-widget elementor-widget-image\" data-id=\"34609324\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"323\" src=\"https:\/\/www.espowercorp.com\/wp-content\/uploads\/2025\/05\/PDU-Rack-19-with-switch-per-unit-copy-2-1024x323.png\" class=\"attachment-large size-large wp-image-14216\" alt=\"PDU-Rack 19 with switch per unit\" srcset=\"https:\/\/www.espowercorp.com\/wp-content\/uploads\/2025\/05\/PDU-Rack-19-with-switch-per-unit-copy-2-1024x323.png 1024w, https:\/\/www.espowercorp.com\/wp-content\/uploads\/2025\/05\/PDU-Rack-19-with-switch-per-unit-copy-2-300x95.png 300w, https:\/\/www.espowercorp.com\/wp-content\/uploads\/2025\/05\/PDU-Rack-19-with-switch-per-unit-copy-2-768x242.png 768w, https:\/\/www.espowercorp.com\/wp-content\/uploads\/2025\/05\/PDU-Rack-19-with-switch-per-unit-copy-2-18x6.png 18w, https:\/\/www.espowercorp.com\/wp-content\/uploads\/2025\/05\/PDU-Rack-19-with-switch-per-unit-copy-2-24x8.png 24w, https:\/\/www.espowercorp.com\/wp-content\/uploads\/2025\/05\/PDU-Rack-19-with-switch-per-unit-copy-2-36x11.png 36w, https:\/\/www.espowercorp.com\/wp-content\/uploads\/2025\/05\/PDU-Rack-19-with-switch-per-unit-copy-2-111x35.png 111w, https:\/\/www.espowercorp.com\/wp-content\/uploads\/2025\/05\/PDU-Rack-19-with-switch-per-unit-copy-2.png 1028w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-65a3263d elementor-section-boxed elementor-section-height-default elementor-section-height-default qodef-elementor-content-no\" data-id=\"65a3263d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-59f7d5d9\" data-id=\"59f7d5d9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-39e3e302 elementor-widget elementor-widget-heading\" data-id=\"39e3e302\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Description<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-14d0b62e elementor-section-boxed elementor-section-height-default elementor-section-height-default qodef-elementor-content-no\" data-id=\"14d0b62e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-144e3c0e\" data-id=\"144e3c0e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-64224742 elementor-widget elementor-widget-text-editor\" data-id=\"64224742\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>AC Power distribution unit (PDU) for rack 19&#8243; (1U) with AC outlet per unit refers to a power strip with individual on-off switches, allowing convenient power control for each outlet. It enhances safety by enabling load monitoring for each connection, reducing the risk of power overload and ensures efficient power distribution and management.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-77141248 elementor-section-boxed elementor-section-height-default elementor-section-height-default qodef-elementor-content-no\" data-id=\"77141248\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7c4516db\" data-id=\"7c4516db\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3f0538f4 elementor-widget elementor-widget-heading\" data-id=\"3f0538f4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Technical Data<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-27e9df76 elementor-widget elementor-widget-image\" data-id=\"27e9df76\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"374\" src=\"https:\/\/www.espowercorp.com\/wp-content\/uploads\/2025\/05\/AC-Power-Distribution-Unit-SW-R_Spec-1024x374.png\" class=\"attachment-large size-large wp-image-14218\" alt=\"AC Power Distribution Unit -SW-R_Spec\" srcset=\"https:\/\/www.espowercorp.com\/wp-content\/uploads\/2025\/05\/AC-Power-Distribution-Unit-SW-R_Spec-1024x374.png 1024w, https:\/\/www.espowercorp.com\/wp-content\/uploads\/2025\/05\/AC-Power-Distribution-Unit-SW-R_Spec-300x110.png 300w, https:\/\/www.espowercorp.com\/wp-content\/uploads\/2025\/05\/AC-Power-Distribution-Unit-SW-R_Spec-768x281.png 768w, https:\/\/www.espowercorp.com\/wp-content\/uploads\/2025\/05\/AC-Power-Distribution-Unit-SW-R_Spec-1536x562.png 1536w, https:\/\/www.espowercorp.com\/wp-content\/uploads\/2025\/05\/AC-Power-Distribution-Unit-SW-R_Spec-18x7.png 18w, https:\/\/www.espowercorp.com\/wp-content\/uploads\/2025\/05\/AC-Power-Distribution-Unit-SW-R_Spec-24x9.png 24w, https:\/\/www.espowercorp.com\/wp-content\/uploads\/2025\/05\/AC-Power-Distribution-Unit-SW-R_Spec-36x13.png 36w, https:\/\/www.espowercorp.com\/wp-content\/uploads\/2025\/05\/AC-Power-Distribution-Unit-SW-R_Spec-96x35.png 96w, https:\/\/www.espowercorp.com\/wp-content\/uploads\/2025\/05\/AC-Power-Distribution-Unit-SW-R_Spec.png 1816w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3642e70a elementor-section-boxed elementor-section-height-default elementor-section-height-default qodef-elementor-content-no\" data-id=\"3642e70a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9245e82\" data-id=\"9245e82\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3e59e344 elementor-section-boxed elementor-section-height-default elementor-section-height-default qodef-elementor-content-no\" data-id=\"3e59e344\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a2ab0ef\" data-id=\"a2ab0ef\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-101ae54f elementor-widget elementor-widget-heading\" data-id=\"101ae54f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Product Coding<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6de50df3 elementor-widget elementor-widget-image\" data-id=\"6de50df3\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"164\" src=\"https:\/\/www.espowercorp.com\/wp-content\/uploads\/2025\/05\/AC-Power-Distribution-Unit-SW-R_Product-Coding-1024x164.png\" class=\"attachment-large size-large wp-image-14219\" alt=\"AC Power Distribution Unit -SW-R_Product Coding\" srcset=\"https:\/\/www.espowercorp.com\/wp-content\/uploads\/2025\/05\/AC-Power-Distribution-Unit-SW-R_Product-Coding-1024x164.png 1024w, https:\/\/www.espowercorp.com\/wp-content\/uploads\/2025\/05\/AC-Power-Distribution-Unit-SW-R_Product-Coding-300x48.png 300w, https:\/\/www.espowercorp.com\/wp-content\/uploads\/2025\/05\/AC-Power-Distribution-Unit-SW-R_Product-Coding-768x123.png 768w, https:\/\/www.espowercorp.com\/wp-content\/uploads\/2025\/05\/AC-Power-Distribution-Unit-SW-R_Product-Coding-1536x246.png 1536w, https:\/\/www.espowercorp.com\/wp-content\/uploads\/2025\/05\/AC-Power-Distribution-Unit-SW-R_Product-Coding-18x3.png 18w, https:\/\/www.espowercorp.com\/wp-content\/uploads\/2025\/05\/AC-Power-Distribution-Unit-SW-R_Product-Coding-24x4.png 24w, https:\/\/www.espowercorp.com\/wp-content\/uploads\/2025\/05\/AC-Power-Distribution-Unit-SW-R_Product-Coding-36x6.png 36w, https:\/\/www.espowercorp.com\/wp-content\/uploads\/2025\/05\/AC-Power-Distribution-Unit-SW-R_Product-Coding-150x24.png 150w, https:\/\/www.espowercorp.com\/wp-content\/uploads\/2025\/05\/AC-Power-Distribution-Unit-SW-R_Product-Coding.png 1958w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-51f2b412 elementor-section-boxed elementor-section-height-default elementor-section-height-default qodef-elementor-content-no\" data-id=\"51f2b412\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c10c00c\" data-id=\"c10c00c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2b53e513 elementor-section-boxed elementor-section-height-default elementor-section-height-default qodef-elementor-content-no\" data-id=\"2b53e513\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5c25cab9\" data-id=\"5c25cab9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-653bc83 elementor-widget elementor-widget-heading\" data-id=\"653bc83\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Dimension<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4b2df40b elementor-widget elementor-widget-image\" data-id=\"4b2df40b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"312\" src=\"https:\/\/www.espowercorp.com\/wp-content\/uploads\/2025\/05\/AC-Power-Distribution-Unit-SW-R_Dimension-1024x312.png\" class=\"attachment-large size-large wp-image-14220\" alt=\"AC Power Distribution Unit -SW-R_Dimension\" srcset=\"https:\/\/www.espowercorp.com\/wp-content\/uploads\/2025\/05\/AC-Power-Distribution-Unit-SW-R_Dimension-1024x312.png 1024w, https:\/\/www.espowercorp.com\/wp-content\/uploads\/2025\/05\/AC-Power-Distribution-Unit-SW-R_Dimension-300x91.png 300w, https:\/\/www.espowercorp.com\/wp-content\/uploads\/2025\/05\/AC-Power-Distribution-Unit-SW-R_Dimension-768x234.png 768w, https:\/\/www.espowercorp.com\/wp-content\/uploads\/2025\/05\/AC-Power-Distribution-Unit-SW-R_Dimension-1536x468.png 1536w, https:\/\/www.espowercorp.com\/wp-content\/uploads\/2025\/05\/AC-Power-Distribution-Unit-SW-R_Dimension-2048x624.png 2048w, https:\/\/www.espowercorp.com\/wp-content\/uploads\/2025\/05\/AC-Power-Distribution-Unit-SW-R_Dimension-18x5.png 18w, https:\/\/www.espowercorp.com\/wp-content\/uploads\/2025\/05\/AC-Power-Distribution-Unit-SW-R_Dimension-24x7.png 24w, https:\/\/www.espowercorp.com\/wp-content\/uploads\/2025\/05\/AC-Power-Distribution-Unit-SW-R_Dimension-36x11.png 36w, https:\/\/www.espowercorp.com\/wp-content\/uploads\/2025\/05\/AC-Power-Distribution-Unit-SW-R_Dimension-115x35.png 115w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fd86d65 elementor-section-boxed elementor-section-height-default elementor-section-height-default qodef-elementor-content-no\" data-id=\"fd86d65\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-31921473\" data-id=\"31921473\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-366165bb elementor-widget elementor-widget-spacer\" data-id=\"366165bb\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-94e1d72 elementor-section-boxed elementor-section-height-default elementor-section-height-default qodef-elementor-content-no\" data-id=\"94e1d72\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4e4069f\" data-id=\"4e4069f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a1aa208 elementor-widget elementor-widget-spacer\" data-id=\"a1aa208\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dec2c02 elementor-section-boxed elementor-section-height-default elementor-section-height-default qodef-elementor-content-no\" data-id=\"dec2c02\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-4cec43a\" data-id=\"4cec43a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-35e3578 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"35e3578\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"https:\/\/drive.google.com\/file\/d\/1o9-s4D3IAzkim2wrO27nDSTor-1iJ1tb\/view?usp=sharing\" target=\"_blank\" download=\"\" id=\"BTN_ESPOWER\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\u0e14\u0e32\u0e27\u0e19\u0e4c\u0e42\u0e2b\u0e25\u0e14\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-8c869cc\" data-id=\"8c869cc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-f8ff144\" data-id=\"f8ff144\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ee1f790 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"ee1f790\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-size-xs\" role=\"button\" id=\"BTN_ESPOWER\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\u0e14\u0e32\u0e27\u0e19\u0e4c\u0e42\u0e2b\u0e25\u0e14\u0e04\u0e39\u0e48\u0e21\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8ed1bbb elementor-section-boxed elementor-section-height-default elementor-section-height-default qodef-elementor-content-no\" data-id=\"8ed1bbb\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7880c06\" data-id=\"7880c06\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5cd9a65 elementor-widget elementor-widget-spacer\" data-id=\"5cd9a65\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>SD-BD-04-01\/Rev.20\/18-03-69 AC POWER DISTRIBUTION (PDU) Description AC Power distribution unit (PDU) for rack 19&#8243; (1U) with AC outlet per unit refers to a power strip with individual on-off switches, allowing convenient power control for each outlet. It enhances safety by enabling load monitoring for each connection, reducing the risk of power overload and ensures efficient [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>AC Power Distribution Unit (SW-R) - ESPOWER<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.espowercorp.com\/en\/ac-power-distribution-unit-pdu\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AC Power Distribution Unit (SW-R) - ESPOWER\" \/>\n<meta property=\"og:description\" content=\"SD-BD-04-01\/Rev.20\/18-03-69 AC POWER DISTRIBUTION (PDU) Description AC Power distribution unit (PDU) for rack 19&#8243; (1U) with AC outlet per unit refers to a power strip with individual on-off switches, allowing convenient power control for each outlet. It enhances safety by enabling load monitoring for each connection, reducing the risk of power overload and ensures efficient [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.espowercorp.com\/en\/ac-power-distribution-unit-pdu\/\" \/>\n<meta property=\"og:site_name\" content=\"ESPOWER\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-08T04:51:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.espowercorp.com\/wp-content\/uploads\/2025\/03\/Nava-logo-1536x526.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.espowercorp.com\/ac-power-distribution-unit-pdu\/\",\"url\":\"https:\/\/www.espowercorp.com\/ac-power-distribution-unit-pdu\/\",\"name\":\"AC Power Distribution Unit (SW-R) - ESPOWER\",\"isPartOf\":{\"@id\":\"https:\/\/www.espowercorp.com\/#website\"},\"datePublished\":\"2025-05-30T03:28:14+00:00\",\"dateModified\":\"2026-04-08T04:51:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.espowercorp.com\/ac-power-distribution-unit-pdu\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.espowercorp.com\/ac-power-distribution-unit-pdu\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.espowercorp.com\/ac-power-distribution-unit-pdu\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"ESPOWER \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e15\u0e39\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14.\",\"item\":\"https:\/\/www.espowercorp.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AC Power Distribution Unit (SW-R)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.espowercorp.com\/#website\",\"url\":\"https:\/\/www.espowercorp.com\/\",\"name\":\"ESPOWER\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.espowercorp.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.espowercorp.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.espowercorp.com\/#organization\",\"name\":\"ESPOWER\",\"url\":\"https:\/\/www.espowercorp.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.espowercorp.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.espowercorp.com\/wp-content\/uploads\/2022\/05\/cropped-ESPOWER.png\",\"contentUrl\":\"https:\/\/www.espowercorp.com\/wp-content\/uploads\/2022\/05\/cropped-ESPOWER.png\",\"width\":1756,\"height\":285,\"caption\":\"ESPOWER\"},\"image\":{\"@id\":\"https:\/\/www.espowercorp.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AC Power Distribution Unit (SW-R) - ESPOWER","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.espowercorp.com\/en\/ac-power-distribution-unit-pdu\/","og_locale":"en_US","og_type":"article","og_title":"AC Power Distribution Unit (SW-R) - ESPOWER","og_description":"SD-BD-04-01\/Rev.20\/18-03-69 AC POWER DISTRIBUTION (PDU) Description AC Power distribution unit (PDU) for rack 19&#8243; (1U) with AC outlet per unit refers to a power strip with individual on-off switches, allowing convenient power control for each outlet. It enhances safety by enabling load monitoring for each connection, reducing the risk of power overload and ensures efficient [&hellip;]","og_url":"https:\/\/www.espowercorp.com\/en\/ac-power-distribution-unit-pdu\/","og_site_name":"ESPOWER","article_modified_time":"2026-04-08T04:51:31+00:00","og_image":[{"url":"https:\/\/www.espowercorp.com\/wp-content\/uploads\/2025\/03\/Nava-logo-1536x526.png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.espowercorp.com\/ac-power-distribution-unit-pdu\/","url":"https:\/\/www.espowercorp.com\/ac-power-distribution-unit-pdu\/","name":"AC Power Distribution Unit (SW-R) - ESPOWER","isPartOf":{"@id":"https:\/\/www.espowercorp.com\/#website"},"datePublished":"2025-05-30T03:28:14+00:00","dateModified":"2026-04-08T04:51:31+00:00","breadcrumb":{"@id":"https:\/\/www.espowercorp.com\/ac-power-distribution-unit-pdu\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.espowercorp.com\/ac-power-distribution-unit-pdu\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.espowercorp.com\/ac-power-distribution-unit-pdu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"ESPOWER \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e15\u0e39\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14.","item":"https:\/\/www.espowercorp.com\/"},{"@type":"ListItem","position":2,"name":"AC Power Distribution Unit (SW-R)"}]},{"@type":"WebSite","@id":"https:\/\/www.espowercorp.com\/#website","url":"https:\/\/www.espowercorp.com\/","name":"ESPOWER","description":"","publisher":{"@id":"https:\/\/www.espowercorp.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.espowercorp.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.espowercorp.com\/#organization","name":"ESPOWER","url":"https:\/\/www.espowercorp.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.espowercorp.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.espowercorp.com\/wp-content\/uploads\/2022\/05\/cropped-ESPOWER.png","contentUrl":"https:\/\/www.espowercorp.com\/wp-content\/uploads\/2022\/05\/cropped-ESPOWER.png","width":1756,"height":285,"caption":"ESPOWER"},"image":{"@id":"https:\/\/www.espowercorp.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.espowercorp.com\/en\/wp-json\/wp\/v2\/pages\/14182"}],"collection":[{"href":"https:\/\/www.espowercorp.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.espowercorp.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.espowercorp.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.espowercorp.com\/en\/wp-json\/wp\/v2\/comments?post=14182"}],"version-history":[{"count":36,"href":"https:\/\/www.espowercorp.com\/en\/wp-json\/wp\/v2\/pages\/14182\/revisions"}],"predecessor-version":[{"id":17892,"href":"https:\/\/www.espowercorp.com\/en\/wp-json\/wp\/v2\/pages\/14182\/revisions\/17892"}],"wp:attachment":[{"href":"https:\/\/www.espowercorp.com\/en\/wp-json\/wp\/v2\/media?parent=14182"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}